{"id":250462,"date":"2025-09-12T16:27:56","date_gmt":"2025-09-12T16:27:56","guid":{"rendered":"https:\/\/northstarfc.com\/?page_id=250462"},"modified":"2025-09-12T16:31:37","modified_gmt":"2025-09-12T16:31:37","slug":"coaching-application","status":"publish","type":"page","link":"https:\/\/northstarfc.com\/es\/resources\/coaching-resources\/coaching-application\/","title":{"rendered":"Solicitud de entrenamiento"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;5px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; custom_padding=&#8221;8px|||||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Work Sans||||||||&#8221; text_text_color=&#8221;#c70101&#8243; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;24px&#8221; header_2_font=&#8221;Source Sans Pro|700|||||||&#8221; header_2_text_color=&#8221;#100707&#8243; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.1em&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;56px&#8221; header_2_font_size_phone=&#8221;40px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_line_height_tablet=&#8221;56px&#8221; header_2_line_height_phone=&#8221;38px&#8221; header_2_line_height_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2><span style=\"color: #85c6e5;\">Coaching Application<\/span><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;1320px&#8221; custom_padding=&#8221;0px||9px||false|false&#8221; custom_css_main_element=&#8221;align-items:center;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_css_main_element=&#8221;align-self: center;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Source Sans Pro||||||||&#8221; text_text_color=&#8221;#100707&#8243; text_font_size=&#8221;20px&#8221; text_line_height=&#8221;24px&#8221; custom_margin=&#8221;||7px||false|false&#8221; custom_padding=&#8221;|30px|||false|false&#8221; hover_enabled=&#8221;0&#8243; custom_css_main_element=&#8221;font-weight:400;&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3><strong>North Star FC Coaching Application<\/strong><\/h3>\n<div class='fluentform ff-default fluentform_wrapper_6 ffs_default_wrap'><form data-form_id=\"6\" id=\"fluentform_6\" class=\"frm-fluent-form fluent_form_6 ff-el-form-top ff_form_instance_6_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_6_1\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Coaching Application<\/legend>        <div\n                style=\"display: none!important; position: absolute!important; transform: translateX(1000%)!important;\"\n                class=\"ff-el-group ff-hpsf-container\"\n        >\n            <div class=\"ff-el-input--label asterisk-right\">\n                <label for=\"ff_6_item_sf\" aria-label=\"Newsletter\">\n                    Newsletter                <\/label>\n            <\/div>\n            <div class=\"ff-el-input--content\">\n                <input type=\"text\"\n                       name=\"item_6__fluent_sf\"\n                       class=\"ff-el-form-control\"\n                       id=\"ff_6_item_sf\"\n                \/>\n            <\/div>\n        <\/div>\n        <input type='hidden' name='__fluent_form_embded_post_id' value='250462' \/><input type=\"hidden\" id=\"_fluentform_6_fluentformnonce\" name=\"_fluentform_6_fluentformnonce\" value=\"c88d86a30c\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/250462\" \/><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_6_names_first_name_' id='label_ff_6_names_first_name_' >First Name<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_6_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"Enter Your First Name\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell '><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_6_names_last_name_' id='label_ff_6_names_last_name_' >Last Name<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[last_name]\" id=\"ff_6_names_last_name_\" class=\"ff-el-form-control\" placeholder=\"Enter Your Last Name\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_6_email' id='label_ff_6_email' aria-label=\"Email\">Email<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_6_email\" class=\"ff-el-form-control\" placeholder=\"Email Address\" data-name=\"email\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_6_phone' id='label_ff_6_phone' aria-label=\"Phone\/Mobile\">Phone\/Mobile<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"Mobile Number\" data-name=\"phone\" id=\"ff_6_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label   aria-label=\"What age groups are you interested in coaching? (Check all that apply)\">What age groups are you interested in coaching? (Check all that apply)<\/label><\/div><div class='ff-el-input--content'><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_1_92f9551642712b2df42120fd573ed943'><input  type=\"checkbox\" name=\"checkbox_1[]\" data-name=\"checkbox_1\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Ages 3-5\"  id='checkbox_1_92f9551642712b2df42120fd573ed943' aria-label='Ages 3-5' aria-invalid='false' aria-required=false> <span>Ages 3-5<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_1_26b716e273688baaa728f9669bc6e5be'><input  type=\"checkbox\" name=\"checkbox_1[]\" data-name=\"checkbox_1\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"U6-U8\"  id='checkbox_1_26b716e273688baaa728f9669bc6e5be' aria-label='U6-U8' aria-invalid='false' aria-required=false> <span>U6-U8<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_1_a636136bece64c88bc4f9ec0f0201af8'><input  type=\"checkbox\" name=\"checkbox_1[]\" data-name=\"checkbox_1\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"U9-U12\"  id='checkbox_1_a636136bece64c88bc4f9ec0f0201af8' aria-label='U9-U12' aria-invalid='false' aria-required=false> <span>U9-U12<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_1_3fe221ca81391e0803c3edc49b0a8d32'><input  type=\"checkbox\" name=\"checkbox_1[]\" data-name=\"checkbox_1\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"U13-U15\"  id='checkbox_1_3fe221ca81391e0803c3edc49b0a8d32' aria-label='U13-U15' aria-invalid='false' aria-required=false> <span>U13-U15<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_1_1c5d2f834000e59c72751a5e147ca113'><input  type=\"checkbox\" name=\"checkbox_1[]\" data-name=\"checkbox_1\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"U16-U19\"  id='checkbox_1_1c5d2f834000e59c72751a5e147ca113' aria-label='U16-U19' aria-invalid='false' aria-required=false> <span>U16-U19<\/span><\/label><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label   aria-label=\"What level are you most comfortable with?\">What level are you most comfortable with?<\/label><\/div><div class='ff-el-input--content'><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_539f3b4062c9b01cd3841ef92895756f'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Competitive (travel)\"  id='checkbox_539f3b4062c9b01cd3841ef92895756f' aria-label='Competitive (travel)' aria-invalid='false' aria-required=false> <span>Competitive (travel)<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_89467d2191f4009bd98545aefb58217f'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Recreational\"  id='checkbox_89467d2191f4009bd98545aefb58217f' aria-label='Recreational' aria-invalid='false' aria-required=false> <span>Recreational<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_d5168f44d927096f3207199f4ae48580'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Youth Classes\"  id='checkbox_d5168f44d927096f3207199f4ae48580' aria-label='Youth Classes' aria-invalid='false' aria-required=false> <span>Youth Classes<\/span><\/label><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_6_input_text' id='label_ff_6_input_text' aria-label=\"Soccer Playing Experience:\">Soccer Playing Experience:<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" data-name=\"input_text\" id=\"ff_6_input_text\"  aria-invalid=\"false\" aria-required=false><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_6_input_text_1' id='label_ff_6_input_text_1' aria-label=\"Coaching Experience (if any):\">Coaching Experience (if any):<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_1\" class=\"ff-el-form-control\" data-name=\"input_text_1\" id=\"ff_6_input_text_1\"  aria-invalid=\"false\" aria-required=false><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label   aria-label=\"Coaching Licenses (if any):\">Coaching Licenses (if any):<\/label><\/div><div class='ff-el-input--content'><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_2_7359bc5ef2efea1f660e0376a60c273d'><input  type=\"checkbox\" name=\"checkbox_2[]\" data-name=\"checkbox_2\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Grassroots\"  id='checkbox_2_7359bc5ef2efea1f660e0376a60c273d' aria-label='Grassroots' aria-invalid='false' aria-required=false> <span>Grassroots<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_2_5ad842bfa809bdfadfe7f4c4bcedf4e4'><input  type=\"checkbox\" name=\"checkbox_2[]\" data-name=\"checkbox_2\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"D License\"  id='checkbox_2_5ad842bfa809bdfadfe7f4c4bcedf4e4' aria-label='D License' aria-invalid='false' aria-required=false> <span>D License<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_2_8f2729e8168c1ee0a27a877bbbc655a1'><input  type=\"checkbox\" name=\"checkbox_2[]\" data-name=\"checkbox_2\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"C License or higher\"  id='checkbox_2_8f2729e8168c1ee0a27a877bbbc655a1' aria-label='C License or higher' aria-invalid='false' aria-required=false> <span>C License or higher<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_2_3fea8ea7f63d1c9f8a1c9fa59b746505'><input  type=\"checkbox\" name=\"checkbox_2[]\" data-name=\"checkbox_2\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Other\"  id='checkbox_2_3fea8ea7f63d1c9f8a1c9fa59b746505' aria-label='Other' aria-invalid='false' aria-required=false> <span>Other<\/span><\/label><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label   aria-label=\"Availability\">Availability<\/label><\/div><div class='ff-el-input--content'><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_3_1881dac204bf8ec7607a80cec576d457'><input  type=\"checkbox\" name=\"checkbox_3[]\" data-name=\"checkbox_3\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Fall\"  id='checkbox_3_1881dac204bf8ec7607a80cec576d457' aria-label='Fall' aria-invalid='false' aria-required=false> <span>Fall<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_3_89c3eeb22b26b7c803f69721d5d5ca2c'><input  type=\"checkbox\" name=\"checkbox_3[]\" data-name=\"checkbox_3\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Winter\"  id='checkbox_3_89c3eeb22b26b7c803f69721d5d5ca2c' aria-label='Winter' aria-invalid='false' aria-required=false> <span>Winter<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_3_d8c2bc2956d0648037de93ed17e507f2'><input  type=\"checkbox\" name=\"checkbox_3[]\" data-name=\"checkbox_3\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Spring\/Summer\"  id='checkbox_3_d8c2bc2956d0648037de93ed17e507f2' aria-label='Spring\/Summer' aria-invalid='false' aria-required=false> <span>Spring\/Summer<\/span><\/label><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_6_description' id='label_ff_6_description' aria-label=\"Why are you interested in coaching for North Star FC?\">Why are you interested in coaching for North Star FC?<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"false\" aria-labelledby=\"label_ff_6_description\" name=\"description\" id=\"ff_6_description\" class=\"ff-el-form-control\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style wpf_has_custom_css\"  aria-label=\"Submit Form\">Submit Form<\/button><\/div><\/fieldset><\/form><div id='fluentform_6_errors' class='ff-errors-in-stack ff_form_instance_6_1 ff-form-loading_errors ff_form_instance_6_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_6_1 = {\"id\":\"6\",\"ajaxUrl\":\"https:\\\/\\\/northstarfc.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"asteriskPlacement\":\"asterisk-right\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_6_1\",\"form_id_selector\":\"fluentform_6\",\"rules\":{\"names[first_name]\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"names[last_name]\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"This field must contain a valid email\",\"global\":true}},\"phone\":{\"required\":{\"value\":true,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"This field is required\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"Phone number is not valid\"}},\"checkbox_1\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"checkbox\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"input_text\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"input_text_1\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"checkbox_2\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"checkbox_3\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"description\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}}},\"debounce_time\":300,\"file_upload_settings\":[]};\n                            <\/script>\n            \n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_enable_image=&#8221;off&#8221; custom_padding_tablet=&#8221;100px||100px||true|false&#8221; custom_padding_phone=&#8221;80px||80px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coaching ApplicationNorth Star FC Coaching Application <div class='fluentform ff-default fluentform_wrapper_6 ffs_default_wrap'><form data-form_id=\"6\" id=\"fluentform_6\" class=\"frm-fluent-form fluent_form_6 ff-el-form-top ff_form_instance_6_2 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_6_2\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Coaching Application<\/legend>        <div\n                style=\"display: none!important; position: absolute!important; transform: translateX(1000%)!important;\"\n                class=\"ff-el-group ff-hpsf-container\"\n        >\n            <div class=\"ff-el-input--label asterisk-right\">\n                <label for=\"ff_6_item_sf\" aria-label=\"Updates\">\n                    Updates                <\/label>\n            <\/div>\n            <div class=\"ff-el-input--content\">\n                <input type=\"text\"\n                       name=\"item_6__fluent_sf\"\n                       class=\"ff-el-form-control\"\n                       id=\"ff_6_item_sf\"\n                \/>\n            <\/div>\n        <\/div>\n        <input type='hidden' name='__fluent_form_embded_post_id' value='250462' \/><input type=\"hidden\" id=\"_fluentform_6_fluentformnonce\" name=\"_fluentform_6_fluentformnonce\" value=\"c88d86a30c\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/250462\" \/><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_6_2_names_first_name_' id='label_ff_6_2_names_first_name_' >First Name<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_6_2_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"Enter Your First Name\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell '><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_6_2_names_last_name_' id='label_ff_6_2_names_last_name_' >Last Name<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[last_name]\" id=\"ff_6_2_names_last_name_\" class=\"ff-el-form-control\" placeholder=\"Enter Your Last Name\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_6_2_email' id='label_ff_6_2_email' aria-label=\"Email\">Email<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_6_2_email\" class=\"ff-el-form-control\" placeholder=\"Email Address\" data-name=\"email\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_6_2_phone' id='label_ff_6_2_phone' aria-label=\"Phone\/Mobile\">Phone\/Mobile<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"Mobile Number\" data-name=\"phone\" id=\"ff_6_2_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label   aria-label=\"What age groups are you interested in coaching? (Check all that apply)\">What age groups are you interested in coaching? (Check all that apply)<\/label><\/div><div class='ff-el-input--content'><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_1_5c1d41778a08dea4e1baa1eeec55c262'><input  type=\"checkbox\" name=\"checkbox_1[]\" data-name=\"checkbox_1\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Ages 3-5\"  id='checkbox_1_5c1d41778a08dea4e1baa1eeec55c262' aria-label='Ages 3-5' aria-invalid='false' aria-required=false> <span>Ages 3-5<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_1_841c65941667f2bd0c3a4401c6f2867e'><input  type=\"checkbox\" name=\"checkbox_1[]\" data-name=\"checkbox_1\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"U6-U8\"  id='checkbox_1_841c65941667f2bd0c3a4401c6f2867e' aria-label='U6-U8' aria-invalid='false' aria-required=false> <span>U6-U8<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_1_3c509265c3bf02cc89940a493dd26ef7'><input  type=\"checkbox\" name=\"checkbox_1[]\" data-name=\"checkbox_1\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"U9-U12\"  id='checkbox_1_3c509265c3bf02cc89940a493dd26ef7' aria-label='U9-U12' aria-invalid='false' aria-required=false> <span>U9-U12<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_1_877c53afe73bffe21460c77c9c2e2676'><input  type=\"checkbox\" name=\"checkbox_1[]\" data-name=\"checkbox_1\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"U13-U15\"  id='checkbox_1_877c53afe73bffe21460c77c9c2e2676' aria-label='U13-U15' aria-invalid='false' aria-required=false> <span>U13-U15<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_1_510514a70de09f97338e9c87ed7453ad'><input  type=\"checkbox\" name=\"checkbox_1[]\" data-name=\"checkbox_1\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"U16-U19\"  id='checkbox_1_510514a70de09f97338e9c87ed7453ad' aria-label='U16-U19' aria-invalid='false' aria-required=false> <span>U16-U19<\/span><\/label><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label   aria-label=\"What level are you most comfortable with?\">What level are you most comfortable with?<\/label><\/div><div class='ff-el-input--content'><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_a9787b55b9b077a7e1196dc4782b0a17'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Competitive (travel)\"  id='checkbox_a9787b55b9b077a7e1196dc4782b0a17' aria-label='Competitive (travel)' aria-invalid='false' aria-required=false> <span>Competitive (travel)<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_75778ad4b44d321ee5a7396c960781a0'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Recreational\"  id='checkbox_75778ad4b44d321ee5a7396c960781a0' aria-label='Recreational' aria-invalid='false' aria-required=false> <span>Recreational<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_1aa6bf8ff6273ed39242d2c021661dbd'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Youth Classes\"  id='checkbox_1aa6bf8ff6273ed39242d2c021661dbd' aria-label='Youth Classes' aria-invalid='false' aria-required=false> <span>Youth Classes<\/span><\/label><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_6_2_input_text' id='label_ff_6_2_input_text' aria-label=\"Soccer Playing Experience:\">Soccer Playing Experience:<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" data-name=\"input_text\" id=\"ff_6_2_input_text\"  aria-invalid=\"false\" aria-required=false><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_6_2_input_text_1' id='label_ff_6_2_input_text_1' aria-label=\"Coaching Experience (if any):\">Coaching Experience (if any):<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_1\" class=\"ff-el-form-control\" data-name=\"input_text_1\" id=\"ff_6_2_input_text_1\"  aria-invalid=\"false\" aria-required=false><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label   aria-label=\"Coaching Licenses (if any):\">Coaching Licenses (if any):<\/label><\/div><div class='ff-el-input--content'><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_2_7bd0e00318a62de4819ab56b1be4e15c'><input  type=\"checkbox\" name=\"checkbox_2[]\" data-name=\"checkbox_2\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Grassroots\"  id='checkbox_2_7bd0e00318a62de4819ab56b1be4e15c' aria-label='Grassroots' aria-invalid='false' aria-required=false> <span>Grassroots<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_2_257b7949ecc004a1355faf85e3c21aad'><input  type=\"checkbox\" name=\"checkbox_2[]\" data-name=\"checkbox_2\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"D License\"  id='checkbox_2_257b7949ecc004a1355faf85e3c21aad' aria-label='D License' aria-invalid='false' aria-required=false> <span>D License<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_2_dad31b18798ceb5c57c95fd63b5d9b92'><input  type=\"checkbox\" name=\"checkbox_2[]\" data-name=\"checkbox_2\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"C License or higher\"  id='checkbox_2_dad31b18798ceb5c57c95fd63b5d9b92' aria-label='C License or higher' aria-invalid='false' aria-required=false> <span>C License or higher<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_2_b7b5088f90674caac19125aa7d446e74'><input  type=\"checkbox\" name=\"checkbox_2[]\" data-name=\"checkbox_2\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Other\"  id='checkbox_2_b7b5088f90674caac19125aa7d446e74' aria-label='Other' aria-invalid='false' aria-required=false> <span>Other<\/span><\/label><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label   aria-label=\"Availability\">Availability<\/label><\/div><div class='ff-el-input--content'><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_3_b9ff303b47cd5edbef5921511c2c3ee1'><input  type=\"checkbox\" name=\"checkbox_3[]\" data-name=\"checkbox_3\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Fall\"  id='checkbox_3_b9ff303b47cd5edbef5921511c2c3ee1' aria-label='Fall' aria-invalid='false' aria-required=false> <span>Fall<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_3_dbec65e2e408c2466cb1a38ec56448fd'><input  type=\"checkbox\" name=\"checkbox_3[]\" data-name=\"checkbox_3\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Winter\"  id='checkbox_3_dbec65e2e408c2466cb1a38ec56448fd' aria-label='Winter' aria-invalid='false' aria-required=false> <span>Winter<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_3_af759c14136190ce6aa2ff32d250c6ff'><input  type=\"checkbox\" name=\"checkbox_3[]\" data-name=\"checkbox_3\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Spring\/Summer\"  id='checkbox_3_af759c14136190ce6aa2ff32d250c6ff' aria-label='Spring\/Summer' aria-invalid='false' aria-required=false> <span>Spring\/Summer<\/span><\/label><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_6_2_description' id='label_ff_6_2_description' aria-label=\"Why are you interested in coaching for North Star FC?\">Why are you interested in coaching for North Star FC?<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"false\" aria-labelledby=\"label_ff_6_2_description\" name=\"description\" id=\"ff_6_2_description\" class=\"ff-el-form-control\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style wpf_has_custom_css\"  aria-label=\"Submit Form\">Submit Form<\/button><\/div><\/fieldset><\/form><div id='fluentform_6_errors' class='ff-errors-in-stack ff_form_instance_6_2 ff-form-loading_errors ff_form_instance_6_2_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_6_2 = {\"id\":\"6\",\"ajaxUrl\":\"https:\\\/\\\/northstarfc.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"asteriskPlacement\":\"asterisk-right\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_6_2\",\"form_id_selector\":\"fluentform_6\",\"rules\":{\"names[first_name]\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"names[last_name]\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"This field must contain a valid email\",\"global\":true}},\"phone\":{\"required\":{\"value\":true,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"This field is required\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"Phone number is not valid\"}},\"checkbox_1\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"checkbox\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"input_text\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"input_text_1\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"checkbox_2\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"checkbox_3\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"description\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}}},\"debounce_time\":300,\"file_upload_settings\":[]};\n                            <\/script>\n            <\/p>\n","protected":false},"author":5,"featured_media":0,"parent":18858,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-250462","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/northstarfc.com\/es\/wp-json\/wp\/v2\/pages\/250462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/northstarfc.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/northstarfc.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/northstarfc.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/northstarfc.com\/es\/wp-json\/wp\/v2\/comments?post=250462"}],"version-history":[{"count":6,"href":"https:\/\/northstarfc.com\/es\/wp-json\/wp\/v2\/pages\/250462\/revisions"}],"predecessor-version":[{"id":250468,"href":"https:\/\/northstarfc.com\/es\/wp-json\/wp\/v2\/pages\/250462\/revisions\/250468"}],"up":[{"embeddable":true,"href":"https:\/\/northstarfc.com\/es\/wp-json\/wp\/v2\/pages\/18858"}],"wp:attachment":[{"href":"https:\/\/northstarfc.com\/es\/wp-json\/wp\/v2\/media?parent=250462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}